{"id":481,"count":2,"description":"","link":"https:\/\/www.relicradio.com\/otr\/series\/american-adventure\/","name":"american adventure","slug":"american-adventure","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>american adventure Archives - Relic Radio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.relicradio.com\/otr\/series\/american-adventure\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"american adventure Archives - Relic Radio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.relicradio.com\/otr\/series\/american-adventure\/\" \/>\n<meta property=\"og:site_name\" content=\"Relic Radio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@RelicRadio\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/series\\\/american-adventure\\\/\",\"url\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/series\\\/american-adventure\\\/\",\"name\":\"american adventure Archives - Relic Radio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/series\\\/american-adventure\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/series\\\/american-adventure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"american adventure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/#website\",\"url\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/\",\"name\":\"Relic Radio\",\"description\":\"Old Time Radio Podcasts\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/#organization\"},\"alternateName\":\"RelicRadio.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/#organization\",\"name\":\"Relic Radio\",\"alternateName\":\"RelicRadio.com\",\"url\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/retmobile23.png\",\"contentUrl\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/retmobile23.png\",\"width\":326,\"height\":100,\"caption\":\"Relic Radio\"},\"image\":{\"@id\":\"https:\\\/\\\/www.relicradio.com\\\/otr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RelicRadioShows\",\"https:\\\/\\\/x.com\\\/RelicRadio\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/RelicRadio\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"american adventure Archives - Relic Radio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.relicradio.com\/otr\/series\/american-adventure\/","og_locale":"en_US","og_type":"article","og_title":"american adventure Archives - Relic Radio","og_url":"https:\/\/www.relicradio.com\/otr\/series\/american-adventure\/","og_site_name":"Relic Radio","twitter_card":"summary_large_image","twitter_site":"@RelicRadio","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.relicradio.com\/otr\/series\/american-adventure\/","url":"https:\/\/www.relicradio.com\/otr\/series\/american-adventure\/","name":"american adventure Archives - Relic Radio","isPartOf":{"@id":"https:\/\/www.relicradio.com\/otr\/#website"},"breadcrumb":{"@id":"https:\/\/www.relicradio.com\/otr\/series\/american-adventure\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.relicradio.com\/otr\/series\/american-adventure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.relicradio.com\/otr\/"},{"@type":"ListItem","position":2,"name":"american adventure"}]},{"@type":"WebSite","@id":"https:\/\/www.relicradio.com\/otr\/#website","url":"https:\/\/www.relicradio.com\/otr\/","name":"Relic Radio","description":"Old Time Radio Podcasts","publisher":{"@id":"https:\/\/www.relicradio.com\/otr\/#organization"},"alternateName":"RelicRadio.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.relicradio.com\/otr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.relicradio.com\/otr\/#organization","name":"Relic Radio","alternateName":"RelicRadio.com","url":"https:\/\/www.relicradio.com\/otr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.relicradio.com\/otr\/#\/schema\/logo\/image\/","url":"https:\/\/www.relicradio.com\/otr\/wp-content\/uploads\/2023\/04\/retmobile23.png","contentUrl":"https:\/\/www.relicradio.com\/otr\/wp-content\/uploads\/2023\/04\/retmobile23.png","width":326,"height":100,"caption":"Relic Radio"},"image":{"@id":"https:\/\/www.relicradio.com\/otr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RelicRadioShows","https:\/\/x.com\/RelicRadio","https:\/\/www.youtube.com\/user\/RelicRadio"]}]}},"_links":{"self":[{"href":"https:\/\/www.relicradio.com\/otr\/wp-json\/wp\/v2\/tags\/481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.relicradio.com\/otr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.relicradio.com\/otr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.relicradio.com\/otr\/wp-json\/wp\/v2\/posts?tags=481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}